﻿

{"id":498,"date":"2016-11-18T09:06:24","date_gmt":"2016-11-18T09:06:24","guid":{"rendered":"http:\/\/ld-wp.template-help.com\/wordpress_64088-sample\/?post_type=mp-event&#038;p=498"},"modified":"2026-02-04T18:34:14","modified_gmt":"2026-02-04T17:34:14","slug":"hatha-yoga","status":"publish","type":"mp-event","link":"https:\/\/yoga-in-wachtberg.de\/en\/timetable\/event\/hatha-yoga\/","title":{"rendered":"Hatha Yoga"},"content":{"rendered":"<p>In den Hatha Yoga Kursen \u00fcben wir kr\u00e4ftigende und entspannende Yoga\u00fcbungen, energetisierende Atem\u00fcbungen sowie die Technik der Tiefenentspannung. Grundlage dieser Kurse ist die sogenannte \u201eRishikesh-Reihe\u201c nach Swami Sivananda, eine aufeinander abgestimmte \u00dcbungsabfolge, welche K\u00f6rper, Geist und Seele harmonisiert. Die Hatha Yoga Kurse erm\u00f6glichen dir einen sehr guten Einstieg in deine Yogapraxis, da sie dir einen Einblick in alle Techniken des Hatha Yoga vermitteln.<\/p>\n<p><strong>Zielgruppe:<\/strong> Anf\u00e4nger, Mittelstufe, Fortgeschrittene<\/p>\n<p><strong>Dauer:<\/strong> Der Kurs findet fortlaufend einmal pro Woche statt. Ein Einstieg ist jederzeit nach <strong>R\u00fccksprache<\/strong> mit Inka m\u00f6glich.<\/p>\n<p><strong>Besonderheit: <\/strong>Dieser Kurs kann sowohl Live im Studio als auch Online \u00fcber Zoom besucht werden.<\/p>\n<p><strong>Kosten:<\/strong><br \/>\nUnitkarte 3 Felder<\/p>\n<p>Bitte habe Verst\u00e4ndnis daf\u00fcr, dass wir deine Yogastunde berechnen, wenn du nicht sp\u00e4testens 24 Stunden vor Beginn absagst. Nur so k\u00f6nnen wir den Platz anderweitig vergeben und unseren Ablauf fair f\u00fcr alle gestalten.<\/p>\n<a href=\"https:\/\/yoga-in-wachtberg.de\/en\/kurse\/\" class=\"su-button su-button-style-ghost\" style=\"color:#FFFFFF;background-color:#8a2046;border-color:#6f1a38;border-radius:0px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 24px;font-size:18px;line-height:36px;border-color:#ae637e;border-radius:0px;text-shadow:0px 0px 0px #000000\"> Zur\u00fcck<\/span><\/a> <a href=\"https:\/\/yoga-in-wachtberg.de\/en\/buchen\/\" class=\"su-button su-button-style-ghost\" style=\"color:#FFFFFF;background-color:#8a2046;border-color:#6f1a38;border-radius:0px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 24px;font-size:18px;line-height:36px;border-color:#ae637e;border-radius:0px;text-shadow:0px 0px 0px #000000\"> Buchen<\/span><\/a>","protected":false},"excerpt":{"rendered":"<p>In den Hatha Yoga Kursen \u00fcben wir kr\u00e4ftigende und entspannende Yoga\u00fcbungen, energetisierende Atem\u00fcbungen sowie die Technik der Tiefenentspannung. Grundlage dieser Kurse ist die sogenannte \u201eRishikesh-Reihe\u201c nach Swami Sivananda, eine aufeinander abgestimmte \u00dcbungsabfolge, welche K\u00f6rper, Geist und Seele harmonisiert. Die Hatha Yoga Kurse erm\u00f6glichen dir einen sehr guten Einstieg in deine Yogapraxis, da sie dir einen &hellip;<\/p>","protected":false},"author":1,"featured_media":1662,"menu_order":0,"template":"","mp-event_category":[47],"mp-event_tag":[],"_links":{"self":[{"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/mp-event\/498"}],"collection":[{"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/mp-event"}],"about":[{"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/types\/mp-event"}],"author":[{"embeddable":true,"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/media\/1662"}],"wp:attachment":[{"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"mp-event_category","embeddable":true,"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/mp-event_category?post=498"},{"taxonomy":"mp-event_tag","embeddable":true,"href":"https:\/\/yoga-in-wachtberg.de\/en\/wp-json\/wp\/v2\/mp-event_tag?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}